{"id":898,"count":2,"description":"","link":"https:\/\/neuropathyreliefmiami.com\/es\/tag\/complicaciones-de-la-neuropatia\/","name":"complicaciones de la neuropat\u00eda","slug":"complicaciones-de-la-neuropatia","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/neuropathyreliefmiami.com\/es\/wp-json\/wp\/v2\/tags\/898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/neuropathyreliefmiami.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/neuropathyreliefmiami.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/neuropathyreliefmiami.com\/es\/wp-json\/wp\/v2\/posts?tags=898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}